{"id":400,"date":"2015-09-29T08:52:39","date_gmt":"2015-09-29T06:52:39","guid":{"rendered":"http:\/\/asdmonticelli.it\/?p=400"},"modified":"2015-09-29T08:52:39","modified_gmt":"2015-09-29T06:52:39","slug":"castelli-contro-la-samb-per-una-bella-giornata-di-sport","status":"publish","type":"post","link":"https:\/\/www.ssdmonticelli.it\/index.php\/2015\/09\/29\/castelli-contro-la-samb-per-una-bella-giornata-di-sport\/","title":{"rendered":"Castelli, contro la Samb per una bella giornata di sport"},"content":{"rendered":"<p>E\u2019 tutto pronto per il primo dei due derby con la Samb e a parlare, alla vigilia dell\u2019impegno di Coppa Italia in programma domani alle 15 allo stadio \u201cRiviera delle Palme\u201d, \u00e8 il direttore generale Francesco Castelli, che coglie l\u2019occasione per lanciare un messaggio alle due tifoserie e stigmatizzare quanto accaduto domenica mattina in un bar di Porto D\u2019Ascoli. Queste le parole del dg: \u201cSperiamo che siano due belle giornate di sport. Per noi \u00e8 un piacere affrontare una squadra blasonata come la Samb, perch\u00e9 mai ci saremmo aspettati di arrivare in serie D e di disputare questo tipo di partite. Per\u00f2, bisogna fare in modo che si possa parlare solo di calcio. La societ\u00e0 del Monticelli ha puntato sempre sulla crescita dei pi\u00f9 giovani e l&#8217;ha fatto mettendo al centro i valori pi\u00f9 puri dello sport e tra questi non c&#8217;\u00e8 sicuramente la violenza. Abbiamo lavorato sempre in questa direzione e il fatto che il nostro pubblico sia formato da tanti bambini e famiglie evidenzia come questa nostra opera sta portando frutti. Il calcio, ma i generale lo sport, deve essere sempre una festa e spiace quando questo non accade.\u00a0Riguardo all\u2019episodio di domenica, infatti, la societ\u00e0 esprime solidariet\u00e0 e vicinanza ai tesserati coinvolti in una vicenda che nulla ha a che fare con il calcio. Ma il nostro obiettivo \u00e8 quello di evidenziare le cose belle dello sport, quindi abbiamo deciso di non tornare sull\u2019argomento anche per stigmatizzarlo, evitando cos\u00ec di esasperare i toni. Storicamente la squadra del Monticelli ha rivestito, all&#8217;interno del quartiere, un forte ruolo sociale. Sono tanti i ragazzi che hanno trovato nella nostra societ\u00e0 un luogo dove crescere prima come persone e poi come calciatori. Anche in Serie D il nostro obiettivo primario rimane questo. Contro la Samb, comunque, ce la metteremo tutta per fare risultato, anche se sappiamo che sar\u00e0 difficile uscire dal Riviera delle Palme con un risultato positiva. In Coppa il mister dar\u00e0 spazio a chi fino ad oggi ha giocato meno, ma la squadra che scender\u00e0 in campo sar\u00e0 comunque in grado di fare una bella figura\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 tutto pronto per il primo dei due derby con la Samb e a parlare, alla vigilia dell\u2019impegno di Coppa Italia in programma domani alle 15 allo stadio \u201cRiviera delle Palme\u201d, \u00e8 il direttore generale Francesco Castelli, che coglie l\u2019occasione per lanciare un messaggio alle due tifoserie e stigmatizzare quanto accaduto domenica mattina in un&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/www.ssdmonticelli.it\/index.php\/2015\/09\/29\/castelli-contro-la-samb-per-una-bella-giornata-di-sport\/\" class=\"excerpt-read-more\">Read More<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-400","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/comments?post=400"}],"version-history":[{"count":1,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/400\/revisions"}],"predecessor-version":[{"id":401,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/400\/revisions\/401"}],"wp:attachment":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/media?parent=400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/categories?post=400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/tags?post=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}