{"id":534,"date":"2015-10-23T10:28:23","date_gmt":"2015-10-23T08:28:23","guid":{"rendered":"http:\/\/asdmonticelli.it\/?p=534"},"modified":"2015-10-23T10:28:23","modified_gmt":"2015-10-23T08:28:23","slug":"minopoli-fiduciosi-e-concentrati-per-riprendere-il-cammino","status":"publish","type":"post","link":"https:\/\/www.ssdmonticelli.it\/index.php\/2015\/10\/23\/minopoli-fiduciosi-e-concentrati-per-riprendere-il-cammino\/","title":{"rendered":"Minopoli: fiduciosi e concentrati per riprendere il cammino"},"content":{"rendered":"<p>Luca Minopoli, esperto centrocampista della squadra di mister Stallone, prova ad analizzare l&#8217;attuale momento della squadra:<\/p>\n<p>&#8220;Nello spogliatoio abbiamo tanta voglia di rifarci e\u00a0c&#8217;\u00e8 la giusta grinta. Non siamo preoccupati perch\u00e8 solo il San Nicol\u00f2 ci ha messo un p\u00f2 in difficolt\u00e0; nelle altre due sconfitte non abbiamo subito, anzi siamo riusciti a imporre comunque il nostro gioco. Sappiamo com&#8217;\u00e8 il calcio, a volte \u00e8 solo un episodio che ti pu\u00f2 condannare. Ci vuole quindi pi\u00f9 concentrazione e il giusto equilibrio: godere si dei bei risultati ma mai esaltarsi.<\/p>\n<p>In categorie come la Serie D si incontrano giocatori formidabili, soprattutto davanti. Giocatori che anche toccando un solo pallone possono farti male. Basta vedere quello che \u00e8 successo a Chieti: loro hanno tirato a porta solo tre volte e sono andati sempre a segno. Per questo motivo le partite bisogna chiuderle prima, domenica scorsa abbiamo avuto diverse occasioni soprattutto quando eravamo in vantaggio per 2-1. Dopo il pareggio l&#8217;inerzia della partita \u00e8 girata dalla loro parte ed \u00e8 andata a finire come tutti sappiamo. Ma siamo fiduciosi perch\u00e8, ripeto, la prestazione c&#8217;\u00e8 stata e se continuiamo cosi i risultati non tarderanno a tornare.<\/p>\n<p>Conoscendo Bolzan, il mister del Castelfidardo, sappiamo che quella che ci aspetta domenica sar\u00e0 una partita durissima. Le sue squadre hanno sempre tanta grinta, ritmo e non mollano mai. Lo scorso anno ha vinto il campionato d&#8217;Eccellenza con la Folgore, una squadra a volte non bellissima ma tosta&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luca Minopoli, esperto centrocampista della squadra di mister Stallone, prova ad analizzare l&#8217;attuale momento della squadra: &#8220;Nello spogliatoio abbiamo tanta voglia di rifarci e\u00a0c&#8217;\u00e8 la giusta grinta. Non siamo preoccupati perch\u00e8 solo il San Nicol\u00f2 ci ha messo un p\u00f2 in difficolt\u00e0; nelle altre due sconfitte non abbiamo subito, anzi siamo riusciti a imporre comunque&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/www.ssdmonticelli.it\/index.php\/2015\/10\/23\/minopoli-fiduciosi-e-concentrati-per-riprendere-il-cammino\/\" class=\"excerpt-read-more\">Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"https:\/\/www.ssdmonticelli.it\/wp-content\/uploads\/2015\/10\/Minopoli.jpg","_links":{"self":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/comments?post=534"}],"version-history":[{"count":2,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/534\/revisions"}],"predecessor-version":[{"id":537,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/534\/revisions\/537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/media\/536"}],"wp:attachment":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/media?parent=534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/categories?post=534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/tags?post=534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}