{"id":550,"date":"2015-10-25T12:55:52","date_gmt":"2015-10-25T10:55:52","guid":{"rendered":"http:\/\/asdmonticelli.it\/?p=550"},"modified":"2015-10-25T12:58:03","modified_gmt":"2015-10-25T10:58:03","slug":"la-juniores-batte-la-capolista","status":"publish","type":"post","link":"https:\/\/www.ssdmonticelli.it\/index.php\/2015\/10\/25\/la-juniores-batte-la-capolista\/","title":{"rendered":"La Juniores batte la capolista"},"content":{"rendered":"<p>Bella vittoria, ieri pomeriggio allo stadio di Venarotta, della Juniores Nazionale guidata da Mister Domenico Natalini contro l&#8217;Amiternina, capolista del girone F. Dopo la battuta d&#8217;arresto sul campo della Folgore Veregra ci si aspettava una prova d&#8217;orgoglio e i giovani biancoazzurri non hanno deluso le aspettative. Dopo essere passati in svantaggio non hanno smesso di giocare e di provare a vincere la partita. Stefano Funari su rigore e Nardinocchi su bell&#8217;assist di Alessio Funari hanno meritatamente ribaltato il risultato.<\/p>\n<p><em>Monticelli &#8211; Amiternina 2-1<\/em><\/p>\n<p>MONTICELLI (4-3-3):\u00a0Orsini; Giorgi, Loreti, Di Matteo, Giacoboni; Funari Alessio, De Berardinis (Chiovini), Funari Stefano (Nardinocchi); Mariani, De Santis, Firmani (Luzi). A disp.\u00a0Silvaggio, Simonetta, Principi, Cavuoti, Gali\u00e8, Virgulti.<\/p>\n<p>RETI: Funari S., Nardinocchi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bella vittoria, ieri pomeriggio allo stadio di Venarotta, della Juniores Nazionale guidata da Mister Domenico Natalini contro l&#8217;Amiternina, capolista del girone F. Dopo la battuta d&#8217;arresto sul campo della Folgore Veregra ci si aspettava una prova d&#8217;orgoglio e i giovani biancoazzurri non hanno deluso le aspettative. Dopo essere passati in svantaggio non hanno smesso di&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/www.ssdmonticelli.it\/index.php\/2015\/10\/25\/la-juniores-batte-la-capolista\/\" class=\"excerpt-read-more\">Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"https:\/\/www.ssdmonticelli.it\/wp-content\/uploads\/2015\/10\/natalini.jpg","_links":{"self":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/comments?post=550"}],"version-history":[{"count":2,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/550\/revisions"}],"predecessor-version":[{"id":553,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/550\/revisions\/553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/media\/551"}],"wp:attachment":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/media?parent=550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/categories?post=550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/tags?post=550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}