{"id":5791,"date":"2021-12-11T09:59:11","date_gmt":"2021-12-11T08:59:11","guid":{"rendered":"http:\/\/www.ssdmonticelli.it\/?p=5791"},"modified":"2021-12-11T09:59:12","modified_gmt":"2021-12-11T08:59:12","slug":"simone-filippini-torna-a-monticelli","status":"publish","type":"post","link":"https:\/\/www.ssdmonticelli.it\/index.php\/2021\/12\/11\/simone-filippini-torna-a-monticelli\/","title":{"rendered":"SIMONE FILIPPINI TORNA A MONTICELLI"},"content":{"rendered":"\n<p>Dopo una prima parte di campionato al Real Metauro, squadra di Prima Categoria di Pesaro, torna a Monticelli Simone Filippini. Classe 2002 cresciuto nei settori giovanili di Ascoli e Monticelli nella scorsa stagione aveva svolto la preparazione estiva con la prima squadra. Pu\u00f2 ricoprire sia il ruolo di esterno di difesa che di centrocampo; torna per dare il suo contributo nel proseguo della stagione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo una prima parte di campionato al Real Metauro, squadra di Prima Categoria di Pesaro, torna a Monticelli Simone Filippini. Classe 2002 cresciuto nei settori giovanili di Ascoli e Monticelli nella scorsa stagione aveva svolto la preparazione estiva con la prima squadra. Pu\u00f2 ricoprire sia il ruolo di esterno di difesa che di centrocampo; torna&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/www.ssdmonticelli.it\/index.php\/2021\/12\/11\/simone-filippini-torna-a-monticelli\/\" class=\"excerpt-read-more\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":5792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[24,26,106],"class_list":["post-5791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-monitcelli","tag-mercato","tag-filippini"],"jetpack_featured_media_url":"https:\/\/www.ssdmonticelli.it\/wp-content\/uploads\/2021\/12\/filippini-sito.jpg","_links":{"self":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/5791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/comments?post=5791"}],"version-history":[{"count":2,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/5791\/revisions"}],"predecessor-version":[{"id":5794,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/posts\/5791\/revisions\/5794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/media\/5792"}],"wp:attachment":[{"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/media?parent=5791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/categories?post=5791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ssdmonticelli.it\/index.php\/wp-json\/wp\/v2\/tags?post=5791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}